{"id":3586,"date":"2023-06-19T14:09:09","date_gmt":"2023-06-19T12:09:09","guid":{"rendered":"https:\/\/archambaud.com\/acerca-de\/"},"modified":"2026-05-29T11:34:46","modified_gmt":"2026-05-29T09:34:46","slug":"acerca-de","status":"publish","type":"page","link":"https:\/\/archambaud.com\/es\/acerca-de\/","title":{"rendered":"Acerca de"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3586\" class=\"elementor elementor-3586 elementor-203\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11e6765 e-flex e-con-boxed e-con e-parent\" data-id=\"11e6765\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eafb3eb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"eafb3eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Una historia de la regi\u00f3n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d9ab34 e-flex e-con-boxed e-con e-parent\" data-id=\"7d9ab34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0fac8d9 e-con-full e-flex e-con e-child\" data-id=\"0fac8d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3518cf8 elementor-widget elementor-widget-image\" data-id=\"3518cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-683x1024.jpg\" class=\"attachment-large size-large wp-image-3602\" alt=\"\" srcset=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-683x1024.jpg 683w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-200x300.jpg 200w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-768x1152.jpg 768w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB.jpg 800w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f63bb65 e-con-full e-flex e-con e-child\" data-id=\"f63bb65\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-140f5e1 elementor-widget elementor-widget-heading\" data-id=\"140f5e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El Bourbonnais, la inspiraci\u00f3n original<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4b01e7 elementor-widget elementor-widget-text-editor\" data-id=\"c4b01e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Entre los siglos X y XI, la regi\u00f3n de Borb\u00f3n, ahora llamada Borbonnais, fue gobernada por una familia de se\u00f1ores durante 6 generaciones, todos llamados Archambaud.<\/p><p>Es en el coraz\u00f3n de esta regi\u00f3n, en el centro de los bosques m\u00e1s bellos de Francia, donde naci\u00f3 el deseo de revivir ciertas tradiciones que recorren este lugar tan rico en historia: la gastronom\u00eda local.<\/p><p>M\u00e1s de 900 a\u00f1os despu\u00e9s, impregnada de la belleza que lo rodea, Archambaud renace de sus llamas creando objetos de excelencia con un dise\u00f1o atemporal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d70906 e-flex e-con-boxed e-con e-parent\" data-id=\"1d70906\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b975d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a8b975d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8aea64c e-flex e-con-boxed e-con e-parent\" data-id=\"8aea64c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96254bb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"96254bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Una historia de pasi\u00f3n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d817efd e-flex e-con-boxed e-con e-parent\" data-id=\"d817efd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-edfc9d7 e-con-full e-flex e-con e-child\" data-id=\"edfc9d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d897c19 elementor-widget elementor-widget-heading\" data-id=\"d897c19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un regreso a las or\u00edgenes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfb2922 elementor-widget elementor-widget-text-editor\" data-id=\"bfb2922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Apasionado por la historia y las artes del fuego, fue en 2020 cuando Dominique Charby, natural de la regi\u00f3n, tom\u00f3 las riendas de la planta para fundar Archambaud, un nuevo s\u00edmbolo de la excepci\u00f3n francesa.<\/p><p>Se rodea de personas apasionadas para desarrollar productos de excelencia que combinen la tradici\u00f3n artesanal y la innovaci\u00f3n tecnol\u00f3gica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-730fbb1 e-con-full e-flex e-con e-child\" data-id=\"730fbb1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d694d0 elementor-widget elementor-widget-image\" data-id=\"8d694d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"748\" src=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/11\/ARCHD_Apropos_1_WEB-1024x958.jpg\" class=\"attachment-large size-large wp-image-3593\" alt=\"\" srcset=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/11\/ARCHD_Apropos_1_WEB-1024x958.jpg 1024w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/11\/ARCHD_Apropos_1_WEB-300x281.jpg 300w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/11\/ARCHD_Apropos_1_WEB-768x719.jpg 768w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/11\/ARCHD_Apropos_1_WEB.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43face3 elementor-widget elementor-widget-heading\" data-id=\"43face3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Dominique Charby,<br \/>Fundador de Archambaud<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5898242 e-flex e-con-boxed e-con e-parent\" data-id=\"5898242\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bf7772 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6bf7772\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los rostros de Archambaud<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4955973 e-grid e-con-boxed e-con e-parent\" data-id=\"4955973\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4dbbcf6 e-con-full e-flex e-con e-child\" data-id=\"4dbbcf6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4d1f5c7 e-con-full e-flex e-con e-child\" data-id=\"4d1f5c7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfd60d2 elementor-widget elementor-widget-heading\" data-id=\"bfd60d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Martha<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c7b3d9 elementor-widget elementor-widget-heading\" data-id=\"0c7b3d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ensamblador artesanal<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e32bec e-con-full e-flex e-con e-child\" data-id=\"5e32bec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-111d46e e-con-full e-flex e-con e-child\" data-id=\"111d46e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e6113b elementor-widget elementor-widget-heading\" data-id=\"1e6113b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Susan<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10bcb80 elementor-widget elementor-widget-heading\" data-id=\"10bcb80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ensamblador artesanal<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a6fe5c e-con-full e-flex e-con e-child\" data-id=\"8a6fe5c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d62a763 e-con-full e-flex e-con e-child\" data-id=\"d62a763\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4655163 elementor-widget elementor-widget-heading\" data-id=\"4655163\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nicholas<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50d095a elementor-widget elementor-widget-heading\" data-id=\"50d095a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Ensamblador artesanal<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63986c6 e-con-full e-flex e-con e-child\" data-id=\"63986c6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7a19621 e-con-full e-flex e-con e-child\" data-id=\"7a19621\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b60f94 elementor-widget elementor-widget-heading\" data-id=\"3b60f94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Bastien<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5145e6b elementor-widget elementor-widget-heading\" data-id=\"5145e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Maestro de taller<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-995c454 e-flex e-con-boxed e-con e-parent\" data-id=\"995c454\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb2afca elementor-widget elementor-widget-image\" data-id=\"eb2afca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"125\" height=\"84\" src=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/11\/Quote.png\" class=\"attachment-large size-large wp-image-3603\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9af655 elementor-widget elementor-widget-heading\" data-id=\"f9af655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\"Estamos muy satisfechos con \u00e9l, es precioso y funciona muy bien.\"<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29efea9 elementor-widget elementor-widget-heading\" data-id=\"29efea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Samuel<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c377b0 e-flex e-con-boxed e-con e-parent\" data-id=\"4c377b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d1c73d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4d1c73d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">De esta historia y esta pasi\u00f3n surgieron nuestras 3 principales cadenas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eaec2dc e-flex e-con-boxed e-con e-parent\" data-id=\"eaec2dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6f1128b e-con-full e-flex e-con e-child\" data-id=\"6f1128b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad7d6a3 elementor-widget elementor-widget-image\" data-id=\"ad7d6a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/archambaud.com\/es\/origen\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"942\" src=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_6_WEB-870x1024.jpg\" class=\"attachment-large size-large wp-image-3604\" alt=\"\" srcset=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_6_WEB-870x1024.jpg 870w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_6_WEB-255x300.jpg 255w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_6_WEB-768x904.jpg 768w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_6_WEB.jpg 1020w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73453b0 elementor-widget elementor-widget-heading\" data-id=\"73453b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/archambaud.com\/es\/origen\/\">Distribuci\u00f3n<br \/> Origen<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37ac53a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"37ac53a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/archambaud.com\/es\/origen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver detalles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4569b95 e-con-full e-flex e-con e-child\" data-id=\"4569b95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62281bf elementor-widget elementor-widget-image\" data-id=\"62281bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/archambaud.com\/legende\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"945\" src=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_4_WEB-867x1024.jpg\" class=\"attachment-large size-large wp-image-3605\" alt=\"\" srcset=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_4_WEB-867x1024.jpg 867w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_4_WEB-254x300.jpg 254w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_4_WEB-768x907.jpg 768w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_4_WEB.jpg 1016w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-816c0b3 elementor-widget elementor-widget-heading\" data-id=\"816c0b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/archambaud.com\/legende\/\">Distribuci\u00f3n<br \/> Leyenda<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f7fba elementor-align-center elementor-widget elementor-widget-button\" data-id=\"17f7fba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/archambaud.com\/legende\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver detalles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0170a83 e-con-full e-flex e-con e-child\" data-id=\"0170a83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bad7bfa elementor-widget elementor-widget-image\" data-id=\"bad7bfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/archambaud.com\/es\/prestigio\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"752\" height=\"1024\" src=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_5_WEB-752x1024.jpg\" class=\"attachment-large size-large wp-image-3606\" alt=\"\" srcset=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_5_WEB-752x1024.jpg 752w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_5_WEB-220x300.jpg 220w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_5_WEB-768x1046.jpg 768w, https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_5_WEB.jpg 881w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89d329e elementor-widget elementor-widget-heading\" data-id=\"89d329e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/archambaud.com\/es\/prestigio\/\">Distribuci\u00f3n<br \/> Prestigio<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2e217e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e2e217e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/archambaud.com\/es\/prestigio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver detalles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed9bd41 e-flex e-con-boxed e-con e-parent\" data-id=\"ed9bd41\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80f1e90 elementor-widget elementor-widget-heading\" data-id=\"80f1e90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cont\u00e1ctanos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4859bab elementor-widget elementor-widget-text-editor\" data-id=\"4859bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Si desea obtener informaci\u00f3n, no dude en ponerse en contacto con nosotros.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-517e859 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"517e859\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/archambaud.com\/es\/contactanos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Una historia de la regi\u00f3n El Bourbonnais, la inspiraci\u00f3n original Entre los siglos X y XI, la regi\u00f3n de Borb\u00f3n, ahora llamada Borbonnais, fue gobernada por una familia de se\u00f1ores durante 6 generaciones, todos llamados Archambaud. Es en el coraz\u00f3n de esta regi\u00f3n, en el centro de los bosques m\u00e1s bellos de Francia, donde naci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3586","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acerca de - Archambaud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archambaud.com\/es\/acerca-de\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acerca de - Archambaud\" \/>\n<meta property=\"og:description\" content=\"Una historia de la regi\u00f3n El Bourbonnais, la inspiraci\u00f3n original Entre los siglos X y XI, la regi\u00f3n de Borb\u00f3n, ahora llamada Borbonnais, fue gobernada por una familia de se\u00f1ores durante 6 generaciones, todos llamados Archambaud. Es en el coraz\u00f3n de esta regi\u00f3n, en el centro de los bosques m\u00e1s bellos de Francia, donde naci\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archambaud.com\/es\/acerca-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Archambaud\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T09:34:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/\",\"url\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/\",\"name\":\"Acerca de - Archambaud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archambaud.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ARCHD_Home_9_WEB-683x1024.jpg\",\"datePublished\":\"2023-06-19T12:09:09+00:00\",\"dateModified\":\"2026-05-29T09:34:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archambaud.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ARCHD_Home_9_WEB-683x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/archambaud.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ARCHD_Home_9_WEB-683x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/acerca-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/archambaud.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acerca de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/archambaud.com\\\/es\\\/\",\"name\":\"Archambaud\",\"description\":\"Manufacture du Bourbonnais\",\"publisher\":{\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archambaud.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/#organization\",\"name\":\"Archambaud\",\"url\":\"https:\\\/\\\/archambaud.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archambaud.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ARCHD_Web_Building_Logo_300522.png\",\"contentUrl\":\"https:\\\/\\\/archambaud.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ARCHD_Web_Building_Logo_300522.png\",\"width\":87,\"height\":110,\"caption\":\"Archambaud\"},\"image\":{\"@id\":\"https:\\\/\\\/archambaud.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acerca de - Archambaud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archambaud.com\/es\/acerca-de\/","og_locale":"es_ES","og_type":"article","og_title":"Acerca de - Archambaud","og_description":"Una historia de la regi\u00f3n El Bourbonnais, la inspiraci\u00f3n original Entre los siglos X y XI, la regi\u00f3n de Borb\u00f3n, ahora llamada Borbonnais, fue gobernada por una familia de se\u00f1ores durante 6 generaciones, todos llamados Archambaud. Es en el coraz\u00f3n de esta regi\u00f3n, en el centro de los bosques m\u00e1s bellos de Francia, donde naci\u00f3 [&hellip;]","og_url":"https:\/\/archambaud.com\/es\/acerca-de\/","og_site_name":"Archambaud","article_modified_time":"2026-05-29T09:34:46+00:00","og_image":[{"width":800,"height":1200,"url":"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/archambaud.com\/es\/acerca-de\/","url":"https:\/\/archambaud.com\/es\/acerca-de\/","name":"Acerca de - Archambaud","isPartOf":{"@id":"https:\/\/archambaud.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archambaud.com\/es\/acerca-de\/#primaryimage"},"image":{"@id":"https:\/\/archambaud.com\/es\/acerca-de\/#primaryimage"},"thumbnailUrl":"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-683x1024.jpg","datePublished":"2023-06-19T12:09:09+00:00","dateModified":"2026-05-29T09:34:46+00:00","breadcrumb":{"@id":"https:\/\/archambaud.com\/es\/acerca-de\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archambaud.com\/es\/acerca-de\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/archambaud.com\/es\/acerca-de\/#primaryimage","url":"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-683x1024.jpg","contentUrl":"https:\/\/archambaud.com\/wp-content\/uploads\/2025\/10\/ARCHD_Home_9_WEB-683x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/archambaud.com\/es\/acerca-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/archambaud.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Acerca de"}]},{"@type":"WebSite","@id":"https:\/\/archambaud.com\/es\/#website","url":"https:\/\/archambaud.com\/es\/","name":"Archambaud","description":"Manufacture du Bourbonnais","publisher":{"@id":"https:\/\/archambaud.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archambaud.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/archambaud.com\/es\/#organization","name":"Archambaud","url":"https:\/\/archambaud.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/archambaud.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/archambaud.com\/wp-content\/uploads\/2022\/05\/ARCHD_Web_Building_Logo_300522.png","contentUrl":"https:\/\/archambaud.com\/wp-content\/uploads\/2022\/05\/ARCHD_Web_Building_Logo_300522.png","width":87,"height":110,"caption":"Archambaud"},"image":{"@id":"https:\/\/archambaud.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/pages\/3586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/comments?post=3586"}],"version-history":[{"count":1,"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/pages\/3586\/revisions"}],"predecessor-version":[{"id":3608,"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/pages\/3586\/revisions\/3608"}],"wp:attachment":[{"href":"https:\/\/archambaud.com\/es\/wp-json\/wp\/v2\/media?parent=3586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}